{"id":1161,"date":"2024-11-08T11:40:35","date_gmt":"2024-11-08T11:40:35","guid":{"rendered":"https:\/\/turnzentrum-bern.ch\/produkt\/bungsringe-mit-deckeninstallation\/"},"modified":"2024-12-07T09:17:34","modified_gmt":"2024-12-07T09:17:34","slug":"uebungsringe-mit-deckeninstallation","status":"publish","type":"product","link":"https:\/\/turnzentrum-bern.ch\/fr\/produit\/uebungsringe-mit-deckeninstallation\/","title":{"rendered":"Anneaux d'entra\u00eenement avec fixation plafond"},"content":{"rendered":"<p>Par ton don, tu apportes une contribution symbolique et tu soutiens le centre de gymnastique de Berne ainsi que de nombreux gymnastes. Un grand merci pour ton engagement !<\/p>","protected":false},"excerpt":{"rendered":"<p>Zum Kraftaufbau als auch gewissen methodischen \u00dcbungen werden \u00dcbungsringe verwendet.<\/p>","protected":false},"featured_media":1415,"template":"","meta":[],"product_brand":[],"product_cat":[28],"product_tag":[],"class_list":{"0":"post-1161","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sponsor_medium","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/turnzentrum-bern.ch\/fr\/wp-json\/wp\/v2\/product\/1161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turnzentrum-bern.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/turnzentrum-bern.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turnzentrum-bern.ch\/fr\/wp-json\/wp\/v2\/media\/1415"}],"wp:attachment":[{"href":"https:\/\/turnzentrum-bern.ch\/fr\/wp-json\/wp\/v2\/media?parent=1161"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/turnzentrum-bern.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=1161"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/turnzentrum-bern.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=1161"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/turnzentrum-bern.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=1161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}